{"id":2,"date":"2024-02-02T12:09:20","date_gmt":"2024-02-02T11:09:20","guid":{"rendered":"http:\/\/librestraits.fr\/?page_id=2"},"modified":"2024-09-10T15:40:45","modified_gmt":"2024-09-10T13:40:45","slug":"page-d-exemple","status":"publish","type":"page","link":"https:\/\/librestraits.fr\/index.php\/page-d-exemple\/","title":{"rendered":"L&rsquo;association"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Libres Traits est une association<\/strong> dont l\u2019objet est de d\u00e9fendre la libert\u00e9 d\u2019expression dans le monde et de promouvoir le dessin de presse et la caricature dans L\u2019Indre.<br>Nous avons \u00e9t\u00e9 nombreux \u00e0 l\u2019origine du salon Papiers d\u2019Actu du Poin\u00e7onnet, manifestation annuelle port\u00e9e par la commune et \u00e0 laquelle nous apportons notre soutien en participant au comit\u00e9 de pilotage et au bon d\u00e9roulement du salon.<br>Nous avons souhait\u00e9, au-del\u00e0 de cette action, \u00e9largir notre intervention en faveur du dessin de presse et de la caricature sur l\u2019ensemble du d\u00e9partement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un partenariat avec la commune du Poin\u00e7onnet et les dessinateurs<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mairie du Poin\u00e7onnet met \u00e0 disposition de l&rsquo;association un fonds de plusieurs milliers de dessins de presse  constitu\u00e9 lors des diff\u00e9rents salons Papiers d&rsquo;Actu depuis 2012.<br>L&rsquo;association sollicite les dessinateurs et la mairie pour constituer ses expositions. <br>L&rsquo;association propose ses expositions aux diff\u00e9rentes structures int\u00e9ress\u00e9es: m\u00e9diath\u00e8ques, associations, \u00e9tablissements scolaires, comit\u00e9s des f\u00eates&#8230;<br>L&rsquo;association peut s&rsquo;adapter pour une demande particuli\u00e8re.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le manifeste de l&rsquo;association<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Promouvoir le dessin de presse, l\u2019humour et la caricature, c\u2019est d\u00e9fendre la libert\u00e9 d\u2019expression et la tol\u00e9rance gravement mises \u00e0 mal par le contr\u00f4le renforc\u00e9 sur les m\u00e9dias par le pouvoir de l\u2019argent, les dictatures et l\u2019intol\u00e9rance religieuse. C\u2019est aussi d\u00e9fendre et prot\u00e9ger les dessinateurs de presse trop souvent menac\u00e9s par le \u00ab moralement correct \u00bb, l\u2019absence d\u2019espaces dans les m\u00e9dias et plus encore par l\u2019obscurantisme, le complotisme, le terrorisme et les dictatures.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le CA et le bureau de l\u2019association sont renouvel\u00e9s tous les ans.<\/strong><br>Les \u00e9lus au bureau&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pr\u00e9sidente&nbsp;: Fran\u00e7oise LAURENT<\/li>\n\n\n\n<li>Vice-Pr\u00e9sident&nbsp;: Jean PETITPRETRE<\/li>\n\n\n\n<li>Tr\u00e9sorier&nbsp;: Jean Clair RAFFALI<\/li>\n\n\n\n<li>Tr\u00e9sorier adjoint&nbsp;: Pascale DESPAX<\/li>\n\n\n\n<li>Secr\u00e9taire&nbsp;: Jackie LAURENT<\/li>\n\n\n\n<li>Secr\u00e9taire adjoint&nbsp;: Pierre JANICAUD<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les r\u00e9unions de bureau sont, la plupart du temps, \u00e9largies au CA et tous les comptes rendus sont envoy\u00e9s aux adh\u00e9rents pour un fonctionnement le plus d\u00e9mocratique possible.<\/li>\n\n\n\n<li>Des groupes de travail ont \u00e9t\u00e9 cr\u00e9\u00e9s.<\/li>\n\n\n\n<li>Un groupe de travail pr\u00e9pare une exposition sur les dessins de la guerre de 14\/18 dans la presse de l\u2019\u00e9poque (Le Pays de France, \u2026).<\/li>\n\n\n\n<li>Un autre groupe g\u00e8re la communication num\u00e9rique (internet, facebook).<\/li>\n\n\n\n<li>D\u2019autres groupes seront organis\u00e9s en fonction des projets du conseil d\u2019administration, des besoins et des propositions. (expositions, interventions etc\u2026).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Libres Traits est une association dont l\u2019objet est de d\u00e9fendre la libert\u00e9 d\u2019expression dans le monde et de promouvoir le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":251,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/librestraits.fr\/index.php\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/librestraits.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/librestraits.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/librestraits.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/librestraits.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":13,"href":"https:\/\/librestraits.fr\/index.php\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":358,"href":"https:\/\/librestraits.fr\/index.php\/wp-json\/wp\/v2\/pages\/2\/revisions\/358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/librestraits.fr\/index.php\/wp-json\/wp\/v2\/media\/251"}],"wp:attachment":[{"href":"https:\/\/librestraits.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}