{"id":12,"count":6,"description":"Libre traits propose des expositions th\u00e9matiques r\u00e9alis\u00e9es \u00e0 partir de caricatures et dessins de presse autour de quelques th\u00e9matiques fortes.\r\nL\u2019association peut \u00e9galement proposer des expositions sur d\u2019autres th\u00e8mes \u00e0 la demande de toute structure int\u00e9ress\u00e9e.\r\n\r\nNos expositions  :\r\n- Le sport (titre provisoire)\r\n- La voix des femmes\r\n- La ruralit\u00e9 aujourd\u2019hui\r\n- L\u2019environnement en question\r\n- Le dessin de presse durant la guerre de 14\/18 (en pr\u00e9paration pour novembre 2024 au Poin\u00e7onnet pour tourner ensuite dans le d\u00e9partement)\r\n\r\nNos expositions possibles : \r\n- La crise financi\u00e8re\r\n- Les conflits modernes\r\n- Bien nourrir la plan\u00e8te\r\n- Tous connect\u00e9s\r\n- Un homme sur deux est une femme\r\n- De murs en fronti\u00e8res : Donald, Wladimir et les autres\r\n- Mai 68 et apr\u00e8s\r\n- Apr\u00e8s #metoo et #balancetonporc, quelle place pour l\u2019homme ?\r\n- Libert\u00e9(s)","link":"https:\/\/librestraits.fr\/index.php\/category\/les-expositions\/","name":"Les expositions","slug":"les-expositions","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/librestraits.fr\/index.php\/wp-json\/wp\/v2\/categories\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/librestraits.fr\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/librestraits.fr\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/librestraits.fr\/index.php\/wp-json\/wp\/v2\/posts?categories=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}